{"id":8976,"date":"2020-07-17T16:35:31","date_gmt":"2020-07-17T19:35:31","guid":{"rendered":"https:\/\/pt-br.sexlog.com\/revista\/?p=8976"},"modified":"2020-07-17T16:35:31","modified_gmt":"2020-07-17T19:35:31","slug":"contos-eroticos-o-primeiro-anal-da-aninha","status":"publish","type":"post","link":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/contos-eroticos-o-primeiro-anal-da-aninha\/","title":{"rendered":"Contos er\u00f3ticos: O primeiro anal da Aninha"},"content":{"rendered":"<p>Vou contar para voc\u00eas como foi a primeira vez que me deliciei com o cuzinho da minha namorada, a Aninha&#8230;<\/p>\n<p>J\u00e1 est\u00e1vamos namorando a algum tempo (apesar de eu ser casado) e as nossas transas estavam se tornando cada vez mais interessantes e gostosas.<\/p>\n<p>O envolvimento emocional era evidente e principalmente por parte de Aninha, que adorava se declarar para mim.<\/p>\n<p>Como j\u00e1 est\u00e1vamos bastante \u00edntimos, em uma de nossas escapadas eu estava delirando com uma chupada espetacular que Aninha estava me proporcionando. Era um boquete maravilhoso, era incr\u00edvel ver aqueles l\u00e1bios carnudos fazendo o contorno da cabe\u00e7a do meu pau, ela chupava t\u00e3o gostoso que eu sentia os espasmos de como se eu estivesse gozando.<\/p>\n<p>Ela lambia toda a extens\u00e3o do meu pau, pegando do saco at\u00e9 a cabe\u00e7a e depois sugava a cabe\u00e7a me arrancando suspiros de tes\u00e3o e prazer.<\/p>\n<p>Sentindo que estava prestes a gozar e estragar a brincadeira, eu mudei de posi\u00e7\u00e3o e comecei a retribuir aquele boquete, sugando sua bucetinha, que era bem apertada cheirosinha, chupava com muito tes\u00e3o e mordia vagarosamente o seu grelinho. Maliciosamente, eu comecei a lamber tamb\u00e9m o cuzinho da safada.<\/p>\n<p>Sentia que ela por algumas vezes resistia e se contorcia com minhas lambidas, ela estava de quatro, ent\u00e3o eu deslizava minha l\u00edngua por toda a grutinha quente at\u00e9 chegar em teu cuzinho e ali eu me demorava um pouco e brincava com minha l\u00edngua em volta do anelzinho.<\/p>\n<p>N\u00e3o aguentando, mais comecei a fuder aquela buceta quente e suculenta, que escorria seu mel lubrificando meu pau e me proporcionando um prazer incr\u00edvel.<\/p>\n<p>Com estocadas firmes e lentas, eu tirava meu pau quase todo e empurrava tudo pra dentro de novo, assim em um ritmo lento, por\u00e9m forte, eu via Aninha rebolando no meu pau e me dizendo que ia gozar. Eu a incentivava e pedia pra ela gozar bem gostoso no meu pau.<\/p>\n<p>Quando ela teve seu primeiro orgasmo eu fiquei ali, atr\u00e1s dela com o meu pau atolado naquela bucetinha gostosa. Dai veio a melhor parte. Eu ali de pau dentro, ela olhou para tr\u00e1s e me perguntou se eu a amava, respondi que sim, ent\u00e3o&#8230; Ela se levantou, pegou um \u00f3leo de massagem e entregou em minhas m\u00e3os, ficou de quatro novamente e me disse que estava na hora de me deixar comer teu cuzinho.<\/p>\n<p>Ela ficou toda empinadinha, eu lambuzei meu pau com o \u00f3leo e esparramei em sua bunda deliciosa e com a ponta do dedo lubrifiquei o teu cuzinho.<\/p>\n<p>Quando posicionei meu pau na entrada, ela empinou mais ainda a bundinha e eu louco de tes\u00e3o segurei bem firme no meu pau e pressionei no cu rosado daquela safada.<\/p>\n<p>Quando entrou a cabe\u00e7a, ela come\u00e7ou a pedir para eu ir devagar e come\u00e7ou a se abaixar e eu pra n\u00e3o sair de dentro. Fui acompanhando seu corpo ficando quase deitado sobre ele que ent\u00e3o ficou de ladinho, j\u00e1 com a metade do meu pau atolado em teu rabo.<\/p>\n<p>Depois de alguns minutos, j\u00e1 sentido que ela estava se acostumando comecei a me movimentar no cu dela, com movimentos curtos e lentos ent\u00e3o ela anunciou que ia gozar outra vez e me pediu pra gozar tamb\u00e9m.<\/p>\n<p>Eu estava alucinado de tes\u00e3o e louco pra encher aquele cu de porra, mas antes eu ainda perguntei o que eu estava comendo. E ela meio t\u00edmida disse que era seu cuzinho. Ent\u00e3o eu disse pra ela falar alto que eu queria ouvir.<\/p>\n<p>Foi quando para minha surpresa ela disse: &#8220;voc\u00ea ta comendo meu cuzinho, bem gostoso. Come vai. Come meu cuzinho&#8221;, gritou pra mim.<\/p>\n<p>Nessa hora n\u00e3o aguentei e gozei bem gostoso naquele rabo delicioso. Na hora de gozar, forcei meu corpo de encontro ao dela e coloquei at\u00e9 o \u00faltimo cent\u00edmetro naquela bunda deliciosa.<\/p>\n<h2 style=\"text-align: center;\"><a href=\"https:\/\/pt-br.sexlog.com\/revista\/envie-seu-depoimento\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Quer ver sua hist\u00f3ria picante publicado na Revista Sexlog?<\/strong><\/a><br \/>\n<a href=\"https:\/\/pt-br.sexlog.com\/revista\/envie-seu-depoimento\" target=\"_blank\" rel=\"noopener noreferrer\">CLIQUE AQUI E ENVIE SUA HIST\u00d3RIA<\/a><\/h2>\n<h2 style=\"text-align: center;\">Conta para n\u00f3s o que achou deste Conto Gr\u00e1tis, comente a\u00ed\u2026<\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Vou contar para voc\u00eas como foi a primeira vez que me deliciei com o cuzinho da minha namorada, a Aninha&#8230; J\u00e1 est\u00e1vamos namorando a algum tempo (apesar de eu ser casado) e as nossas transas estavam se tornando cada vez mais interessantes e gostosas. O envolvimento emocional era evidente e principalmente por parte de Aninha, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":10856,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[580],"tags":[],"class_list":["post-8976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-contos-eroticos-sexlog-historias-reais","entry","has-media"],"_links":{"self":[{"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/posts\/8976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/comments?post=8976"}],"version-history":[{"count":2,"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/posts\/8976\/revisions"}],"predecessor-version":[{"id":10857,"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/posts\/8976\/revisions\/10857"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/media\/10856"}],"wp:attachment":[{"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/media?parent=8976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/categories?post=8976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pt-br.sexlog.com\/contos-eroticos\/wp-json\/wp\/v2\/tags?post=8976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}